{"id":19381,"date":"2018-10-02T16:22:00","date_gmt":"2018-10-02T15:22:00","guid":{"rendered":"https:\/\/dynamitebaits.com\/de\/?p=19381"},"modified":"2018-10-02T17:00:48","modified_gmt":"2018-10-02T16:00:48","slug":"a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker","status":"publish","type":"post","link":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/","title":{"rendered":"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker"},"content":{"rendered":"<p>T\u00fct, t\u00fct&#8230;. Die letzte Nacht der World Carp Classic 2018 ist angebrochen und es war kurz vor 21Uhr als unser Hd5 Empf\u00e4nger von CarpSpirit zum ersten Mal seit 2 Tagen ert\u00f6nte, nur 2 mal kam ein kurzes Signal. Wir schauten uns an und waren erstarrt und fragten uns, war das jetzt ein Biss oder doch nur der Wind, Kraut oder einer der vielen Schw\u00e4ne.<\/p>\n<p>Einige Sekunden darauf sagte Ren\u00e9: \u201eKomm wir m\u00fcssen die Rute kontrollieren!\u201c<br>\nIch zog mir die Wathose an und Ren\u00e8 sprang in seine Gummistiefel. Am Weg zu den Ruten erklang der Bissanzeiger erneut. Was f\u00fcr ein Gef\u00fchl, nach 2 Tagen ohne Biss, nun war es sicher. Fish on!<br>\nRen\u00e9 stieg ins Black Boot und ich schlug die Rute an und dann ging es los&#8230;<\/p>\n<p>Die weiteren Worte sind von Ren\u00e9 und seinem Erlebnis mit dem Drill am Boot:<br>\nKnappe 300m Meter rudern, da es aufgrund der emensen Krautmengen bis an die Oberfl\u00e4che fast unm\u00f6glich war mit dem Motor zufahren. Am Weg zum Fisch musste ich mehrmals die Schnur vom Kraut befreien. Meine Gedanken immer wieder \u201eBitte bitte sei noch dran\u201c. Endlich war ich an der Stelle angelangt wo ich auch die Montage platziert hatte, die Schnur ging jedoch stark nach rechts. Ich paddelte also weiter in Richtung Fisch, hatte jedoch keinen Druck mehr auf der Rute und es kam ein richtig gro\u00dfes Krautb\u00fcndel an die Oberfl\u00e4che. \u201eWir haben ihn verloren\u201c, dachte ich nur. Ich befreite erneut die Schnur vom Kraut als pl\u00f6tzlich zwei Mal ein Druck zu sp\u00fcren war. \u201eYes, er ist noch da!!\u201c<\/p>\n<p>Ich pumpte ihn ganz leicht und mit viel Gef\u00fchl in die H\u00f6he und er kam schnell an die Oberfl\u00e4che. \u201eWow was f\u00fcr ein geiler Fisch\u201c. Eine Windb\u00f6e kam genau in dem Moment als ich ihn keschern wollte, also schnell den Kescher unter Wasser gedr\u00fcckt damit ich ihn nicht absto\u00dfe, der Fisch n\u00fctzte die Gelegenheit und verschwand wieder im Kraut. Ich paddelte zu ihm, lie\u00df ihn an die Oberfl\u00e4che zur\u00fcckkommen und kescherte ihn sofort. Diesmal mit Erfolg!<\/p>\n<div id=\"attachment_19382\" style=\"width: 1010px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg\" data-rel=\"lightbox-image-0\" data-rl_title data-rl_caption title><noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19382\" class=\"wp-image-19382 size-full\" src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg\" alt width=\"1000\" height=\"887\" srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg 1000w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg-300x266.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg-768x681.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"><\/noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19382\" class=\"wp-image-19382 size-full lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201000%20887%22%3E%3C%2Fsvg%3E\" alt width=\"1000\" height=\"887\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201000%20887%22%3E%3C%2Fsvg%3E 1000w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg 1000w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg-300x266.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg-768x681.jpg 768w\" data-src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg\"><\/a><p id=\"caption-attachment-19382\" class=\"wp-caption-text\">Wir haben es geschafft zum 20. Jubil\u00e4um der World Carp Classic auch noch den Rekord f\u00fcr den Schwersten Fisch zu brechen<\/p><\/div>\n<p>Er ist im Kescher. YES! Mit ihm auch ein gro\u00dfer Haufen an Kraut, welches ihn noch bedeckte. Zu dem Zeitpunkt war mit noch nicht klar was f\u00fcr ein geiler Fisch das ist.<br>\nIch hakte ihn gleich im Kescher aus und da sah ich zum erstem Mal das gro\u00dfe Maul. Danach befreite ich ihm von dem ganzen Kraut und ja was soll ich sagen, er wurde einfach immer gr\u00f6\u00dfer und gr\u00f6\u00dfer, immer mehr kam seine volle Pracht zum Vorschein.<\/p>\n<p>Diesen Bullen alleine ins Boot zu heben, war schon extrem und ein unbeschreibliches Gef\u00fchl.<\/p>\n<p>Den Fisch dann sicher im Boot schrie ich nur noch vor Gl\u00fcck \u201eDanke, danke, danke!\u201c und blickte nach oben.<\/p>\n<p>Unser Erfolgsrig war das einfache D-Rig. Wir haben daf\u00fcr ausschlie\u00dflich Produkte von Carpspirit in Verwendung wie unter anderem das Re-Action Vorfach Material 0,25lb und einem Razor Point Medium Curve Shank Gr. 2. Unser Futter als auch K\u00f6der war nat\u00fcrlich von der Firma Dynamite. An diesem Haar war eine <a href=\"https:\/\/dynamitebaits.com\/de\/product\/source-26mm-boilies\/\">26mm Source<\/a> in Kombination mit einer halben <a href=\"https:\/\/dynamitebaits.com\/de\/product\/the-crave-boilies\/\">26mm Crave<\/a> Kugel.<\/p>\n<div id=\"attachment_19391\" style=\"width: 1010px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave.jpg\" data-rel=\"lightbox-image-1\" data-rl_title data-rl_caption title><noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19391\" class=\"size-full wp-image-19391\" src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave.jpg\" alt width=\"1000\" height=\"662\" srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave.jpg 1000w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave-300x199.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave-768x508.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"><\/noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19391\" class=\"size-full wp-image-19391 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201000%20662%22%3E%3C%2Fsvg%3E\" alt width=\"1000\" height=\"662\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201000%20662%22%3E%3C%2Fsvg%3E 1000w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave.jpg 1000w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave-300x199.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave-768x508.jpg 768w\" data-src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Source-Crave.jpg\"><\/a><p id=\"caption-attachment-19391\" class=\"wp-caption-text\">Source &amp; Crave 26mm<\/p><\/div>\n<p>Als dann noch die Waage auf \u00fcber 29kg schlug konnten wir es fast nicht glauben und wussten noch gar nicht was dies bedeutet. Es war ein unglaubliches Gef\u00fchl und wird uns immer in Erinnerung bleiben. Mit dem Schlusspfiff war es dann sogar offiziell, wir haben es geschafft zum 20. Jubil\u00e4um der World Carp Classic auch noch den Rekord f\u00fcr den Schwersten Fisch zu brechen. Zum ersten Mal in der Geschichte der WCC hat es ein \u00f6sterreichisches Team geschafft sich zu verewigen. Wir sind sehr stolz darauf.<\/p>\n<p>Thank you Madine<\/p>\n<div id=\"attachment_19393\" style=\"width: 1290px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record.jpg\" data-rel=\"lightbox-image-2\" data-rl_title data-rl_caption title><noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19393\" class=\"size-full wp-image-19393\" src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record.jpg\" alt width=\"1280\" height=\"853\" srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record.jpg 1280w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record-300x200.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record-768x512.jpg 768w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record-1024x682.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\"><\/noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19393\" class=\"size-full wp-image-19393 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201280%20853%22%3E%3C%2Fsvg%3E\" alt width=\"1280\" height=\"853\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201280%20853%22%3E%3C%2Fsvg%3E 1280w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record.jpg 1280w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record-300x200.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record-768x512.jpg 768w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record-1024x682.jpg 1024w\" data-src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Dynamite-WCC-record.jpg\"><\/a><p id=\"caption-attachment-19393\" class=\"wp-caption-text\">29,8kg<\/p><\/div>\n<div id=\"attachment_19383\" style=\"width: 1290px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit.jpg\" data-rel=\"lightbox-image-3\" data-rl_title data-rl_caption title><noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19383\" class=\"size-full wp-image-19383\" src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit.jpg\" alt width=\"1280\" height=\"853\" srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit.jpg 1280w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit-300x200.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit-768x512.jpg 768w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit-1024x682.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\"><\/noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19383\" class=\"size-full wp-image-19383 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201280%20853%22%3E%3C%2Fsvg%3E\" alt width=\"1280\" height=\"853\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201280%20853%22%3E%3C%2Fsvg%3E 1280w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit.jpg 1280w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit-300x200.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit-768x512.jpg 768w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit-1024x682.jpg 1024w\" data-src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Jasmine-Schuster-Rene-Jauker-Dynamite-Carp-Spirit.jpg\"><\/a><p id=\"caption-attachment-19383\" class=\"wp-caption-text\">Jasmine Schuster &amp; Rene Jauker Dynamite Carp Spirit<\/p><\/div>\n<div id=\"attachment_19392\" style=\"width: 754px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/42608152_10214056438298388_147854906294796288_n.jpg\" data-rel=\"lightbox-image-4\" data-rl_title data-rl_caption title><noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19392\" class=\"size-full wp-image-19392\" src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/42608152_10214056438298388_147854906294796288_n.jpg\" alt width=\"744\" height=\"510\" srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/42608152_10214056438298388_147854906294796288_n.jpg 744w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/42608152_10214056438298388_147854906294796288_n-300x206.jpg 300w\" sizes=\"(max-width: 744px) 100vw, 744px\"><\/noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-19392\" class=\"size-full wp-image-19392 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20744%20510%22%3E%3C%2Fsvg%3E\" alt width=\"744\" height=\"510\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20744%20510%22%3E%3C%2Fsvg%3E 744w\" sizes=\"(max-width: 744px) 100vw, 744px\" data-srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/42608152_10214056438298388_147854906294796288_n.jpg 744w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/42608152_10214056438298388_147854906294796288_n-300x206.jpg 300w\" data-src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/42608152_10214056438298388_147854906294796288_n.jpg\"><\/a><p id=\"caption-attachment-19392\" class=\"wp-caption-text\">Big Kiss for a big Fish<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>T\u00fct, t\u00fct&#8230;. Die letzte Nacht der World Carp Classic 2018 ist angebrochen und es war kurz vor 21Uhr als unser Hd5 Empf\u00e4nger von CarpSpirit zum [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[118,124,125],"tags":[],"class_list":["post-19381","post","type-post","status-publish","format-standard","hentry","category-karpfen","category-artikel","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker - Dynamite Baits Germany<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker - Dynamite Baits Germany\" \/>\n<meta property=\"og:description\" content=\"T\u00fct, t\u00fct&#8230;. Die letzte Nacht der World Carp Classic 2018 ist angebrochen und es war kurz vor 21Uhr als unser Hd5 Empf\u00e4nger von CarpSpirit zum [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/\" \/>\n<meta property=\"og:site_name\" content=\"Dynamite Baits Germany\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-02T15:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-02T16:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg\" \/>\n<meta name=\"author\" content=\"Dynamite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dynamite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/\"},\"author\":{\"name\":\"Dynamite\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/#\\\/schema\\\/person\\\/dc7b7e58d113f099db987039a3677334\"},\"headline\":\"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker\",\"datePublished\":\"2018-10-02T15:22:00+00:00\",\"dateModified\":\"2018-10-02T16:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/\"},\"wordCount\":713,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/10\\\/Rene-Jauker-WCC-29kg.jpg\",\"articleSection\":[\"Karpfen\",\"Artikel\",\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/\",\"url\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/\",\"name\":\"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker - Dynamite Baits Germany\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/10\\\/Rene-Jauker-WCC-29kg.jpg\",\"datePublished\":\"2018-10-02T15:22:00+00:00\",\"dateModified\":\"2018-10-02T16:00:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/#\\\/schema\\\/person\\\/dc7b7e58d113f099db987039a3677334\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/10\\\/Rene-Jauker-WCC-29kg.jpg\",\"contentUrl\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/10\\\/Rene-Jauker-WCC-29kg.jpg\",\"width\":1000,\"height\":887,\"caption\":\"Rene Jauker WCC 29kg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/artikel\\\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/\",\"name\":\"Dynamite Baits Germany\",\"description\":\"Rolled by Anglers for Anglers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/#\\\/schema\\\/person\\\/dc7b7e58d113f099db987039a3677334\",\"name\":\"Dynamite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d9367eef0b93da1368e488d4cef631ceb58365bffa8f33998fd062765edf494?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d9367eef0b93da1368e488d4cef631ceb58365bffa8f33998fd062765edf494?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d9367eef0b93da1368e488d4cef631ceb58365bffa8f33998fd062765edf494?s=96&d=mm&r=g\",\"caption\":\"Dynamite\"},\"sameAs\":[\"http:\\\/\\\/Dynamite%20Baits\"],\"url\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/author\\\/andrewbaker\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker - Dynamite Baits Germany","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/","og_locale":"de_DE","og_type":"article","og_title":"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker - Dynamite Baits Germany","og_description":"T\u00fct, t\u00fct&#8230;. Die letzte Nacht der World Carp Classic 2018 ist angebrochen und es war kurz vor 21Uhr als unser Hd5 Empf\u00e4nger von CarpSpirit zum [&hellip;]","og_url":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/","og_site_name":"Dynamite Baits Germany","article_published_time":"2018-10-02T15:22:00+00:00","article_modified_time":"2018-10-02T16:00:48+00:00","og_image":[{"url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg","type":"","width":"","height":""}],"author":"Dynamite","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dynamite","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/#article","isPartOf":{"@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/"},"author":{"name":"Dynamite","@id":"https:\/\/dynamitebaits.com\/de\/#\/schema\/person\/dc7b7e58d113f099db987039a3677334"},"headline":"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker","datePublished":"2018-10-02T15:22:00+00:00","dateModified":"2018-10-02T16:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/"},"wordCount":713,"commentCount":0,"image":{"@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/#primaryimage"},"thumbnailUrl":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg","articleSection":["Karpfen","Artikel","News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/","url":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/","name":"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker - Dynamite Baits Germany","isPartOf":{"@id":"https:\/\/dynamitebaits.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/#primaryimage"},"image":{"@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/#primaryimage"},"thumbnailUrl":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg","datePublished":"2018-10-02T15:22:00+00:00","dateModified":"2018-10-02T16:00:48+00:00","author":{"@id":"https:\/\/dynamitebaits.com\/de\/#\/schema\/person\/dc7b7e58d113f099db987039a3677334"},"breadcrumb":{"@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/#primaryimage","url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg","contentUrl":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2018\/10\/Rene-Jauker-WCC-29kg.jpg","width":1000,"height":887,"caption":"Rene Jauker WCC 29kg"},{"@type":"BreadcrumbList","@id":"https:\/\/dynamitebaits.com\/de\/artikel\/a-big-kiss-for-a-big-fish-von-jasmine-schuster-and-rene-jauker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dynamitebaits.com\/de\/"},{"@type":"ListItem","position":2,"name":"A big Kiss for a big Fish von Jasmine Schuster and Ren\u00e9 Jauker"}]},{"@type":"WebSite","@id":"https:\/\/dynamitebaits.com\/de\/#website","url":"https:\/\/dynamitebaits.com\/de\/","name":"Dynamite Baits Germany","description":"Rolled by Anglers for Anglers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dynamitebaits.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/dynamitebaits.com\/de\/#\/schema\/person\/dc7b7e58d113f099db987039a3677334","name":"Dynamite","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9d9367eef0b93da1368e488d4cef631ceb58365bffa8f33998fd062765edf494?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d9367eef0b93da1368e488d4cef631ceb58365bffa8f33998fd062765edf494?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d9367eef0b93da1368e488d4cef631ceb58365bffa8f33998fd062765edf494?s=96&d=mm&r=g","caption":"Dynamite"},"sameAs":["http:\/\/Dynamite%20Baits"],"url":"https:\/\/dynamitebaits.com\/de\/author\/andrewbaker\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:05:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/posts\/19381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/comments?post=19381"}],"version-history":[{"count":0,"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/posts\/19381\/revisions"}],"wp:attachment":[{"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/media?parent=19381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/categories?post=19381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/tags?post=19381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}