{"id":5438,"date":"2017-03-08T13:33:53","date_gmt":"2017-03-08T13:33:53","guid":{"rendered":"http:\/\/79.170.44.101\/dynamitebaits.kinsta.cloud\/wp-content\/uploads\/2017\/03\/Ross-Ryder-2-1.jpg"},"modified":"2017-03-08T13:33:53","modified_gmt":"2017-03-08T13:33:53","slug":"ross-ryder-2-2","status":"inherit","type":"attachment","link":"https:\/\/dynamitebaits.com\/de\/anglers\/ross-ryder\/attachment\/ross-ryder-2-2\/","title":{"rendered":"Ross Ryder 2"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-5438","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ross Ryder 2 - Dynamite Baits Germany<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ross Ryder 2 - Dynamite Baits Germany\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Dynamite Baits Germany\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/03\\\/Ross-Ryder-2-1.jpg\",\"url\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/03\\\/Ross-Ryder-2-1.jpg\",\"name\":\"Ross Ryder 2 - Dynamite Baits Germany\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/#website\"},\"datePublished\":\"2017-03-08T13:33:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/03\\\/Ross-Ryder-2-1.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/03\\\/Ross-Ryder-2-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/03\\\/Ross-Ryder-2-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ross Ryder\",\"item\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/anglers\\\/ross-ryder\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ross Ryder 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/\",\"name\":\"Dynamite Baits Germany\",\"description\":\"Rolled by Anglers for Anglers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dynamitebaits.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ross Ryder 2 - Dynamite Baits Germany","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg","og_locale":"de_DE","og_type":"article","og_title":"Ross Ryder 2 - Dynamite Baits Germany","og_url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg","og_site_name":"Dynamite Baits Germany","og_image":[{"width":1280,"height":853,"url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg","url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg","name":"Ross Ryder 2 - Dynamite Baits Germany","isPartOf":{"@id":"https:\/\/dynamitebaits.com\/de\/#website"},"datePublished":"2017-03-08T13:33:53+00:00","breadcrumb":{"@id":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dynamitebaits.com\/de\/"},{"@type":"ListItem","position":2,"name":"Ross Ryder","item":"https:\/\/dynamitebaits.com\/de\/anglers\/ross-ryder\/"},{"@type":"ListItem","position":3,"name":"Ross Ryder 2"}]},{"@type":"WebSite","@id":"https:\/\/dynamitebaits.com\/de\/#website","url":"https:\/\/dynamitebaits.com\/de\/","name":"Dynamite Baits Germany","description":"Rolled by Anglers for Anglers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dynamitebaits.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg\" title data-rl_title class=\"rl-gallery-link\" data-rl_caption data-rel=\"lightbox-gallery-0\"><noscript><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-300x200.jpg\" class=\"attachment-medium size-medium\" alt srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-300x200.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-768x512.jpg 768w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-1024x683.jpg 1024w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\"><\/noscript><img decoding=\"async\" width=\"300\" height=\"200\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20300%20200%22%3E%3C%2Fsvg%3E\" class=\"attachment-medium size-medium lazyload\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20300%20200%22%3E%3C%2Fsvg%3E 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-srcset=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-300x200.jpg 300w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-768x512.jpg 768w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-1024x683.jpg 1024w, https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg 1280w\" data-src=\"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-300x200.jpg\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":853,"file":"2017\/03\/Ross-Ryder-2-1.jpg","sizes":{"thumbnail":{"file":"Ross-Ryder-2-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-150x150.jpg"},"medium":{"file":"Ross-Ryder-2-1-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-300x200.jpg"},"medium_large":{"file":"Ross-Ryder-2-1-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-768x512.jpg"},"large":{"file":"Ross-Ryder-2-1-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1-1024x683.jpg"},"full":{"file":"Ross-Ryder-2-1.jpg","width":1280,"height":853,"mime_type":"image\/jpeg","source_url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5427,"source_url":"https:\/\/dynamitebaits.com\/de\/wp-content\/uploads\/sites\/5\/2017\/03\/Ross-Ryder-2-1.jpg","filename":"Ross-Ryder-2-1.jpg","filesize":147903,"_links":{"self":[{"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/media\/5438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/comments?post=5438"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":5427,"href":"https:\/\/dynamitebaits.com\/de\/wp-json\/wp\/v2\/posts\/5427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}